{"id":12912,"date":"2023-12-26T02:50:06","date_gmt":"2023-12-25T23:50:06","guid":{"rendered":"https:\/\/enderg.com\/?post_type=product&#038;p=12912"},"modified":"2024-09-30T13:52:17","modified_gmt":"2024-09-30T10:52:17","slug":"buy-marvels-spider-man-2","status":"publish","type":"product","link":"https:\/\/enderg.com\/es\/product\/buy-marvels-spider-man-2\/","title":{"rendered":"Marvel&#039;s Spider-Man 2"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"12912\" class=\"elementor elementor-12912\" data-elementor-post-type=\"product\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5463f7c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5463f7c8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e4af85e\" data-id=\"7e4af85e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44b97c8d elementor-widget elementor-widget-accordion\" data-id=\"44b97c8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1151\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1151\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-truck\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-truck\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Entrega r\u00e1pida<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\t<div id=\"elementor-tab-content-1151\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1151\"><p>\u00a1Los pedidos se enviar\u00e1n lo m\u00e1s r\u00e1pido posible durante nuestro horario comercial! De\u00a0<strong><em>De 9AM a 11:59 PM GMT<\/em><\/strong><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73a6d231 elementor-widget elementor-widget-accordion\" data-id=\"73a6d231\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1941\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1941\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fab fa-playstation\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fab fa-playstation\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">C\u00f3mo activar<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\t<div id=\"elementor-tab-content-1941\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1941\"><div class=\"summary__title\"><div class=\"summary__title\"><p>En el momento de la entrega, recibir\u00e1 la &#039;Suscripci\u00f3n&#039; o el &#039;Juego&#039; que solicit\u00f3, pero debe activarse &#039;Agregando&#039; una &#039;Cuenta nueva&#039; a su consola.<\/p><p><span style=\"color: #ffde59;\"><strong>No hay necesidad<\/strong><\/span> \u00a1Crear o jugar en una nueva cuenta! El juego se podr\u00e1 jugar en tu cuenta. <span style=\"color: #ffde59;\"><strong>Cuenta personal<\/strong><\/span>!<\/p><div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\"><div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\"><img decoding=\"async\" data-attachment-id=\"7325\" data-permalink=\"https:\/\/enderg.com\/es\/?attachment_id=7325\" data-orig-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?fit=512%2C512&amp;ssl=1\" data-orig-size=\"512,512\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"tick wd\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?fit=512%2C512&amp;ssl=1\" class=\"alignleft wp-image-7325 ls-is-cached lazyloaded\" src=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=25%2C25&amp;ssl=1\" sizes=\"(max-width: 25px) 100vw, 25px\" srcset=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=416%2C416&amp;ssl=1 416w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=50%2C50&amp;ssl=1 50w\" alt=\"\" width=\"25\" height=\"25\" data-medium-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?fit=300%2C300&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=25%2C25&amp;ssl=1\" \/><\/div><div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\">\u00a1Ahorra m\u00e1s de la mitad del precio regular!<\/div><div aria-hidden=\"true\">\u00a0<\/div><div aria-hidden=\"true\"><div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\"><img decoding=\"async\" data-attachment-id=\"7325\" data-permalink=\"https:\/\/enderg.com\/es\/?attachment_id=7325\" data-orig-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?fit=512%2C512&amp;ssl=1\" data-orig-size=\"512,512\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"tick wd\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?fit=512%2C512&amp;ssl=1\" class=\"alignleft wp-image-7325 ls-is-cached lazyloaded\" src=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=25%2C25&amp;ssl=1\" sizes=\"(max-width: 25px) 100vw, 25px\" srcset=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=416%2C416&amp;ssl=1 416w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=50%2C50&amp;ssl=1 50w\" alt=\"\" width=\"25\" height=\"25\" data-medium-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?fit=300%2C300&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=25%2C25&amp;ssl=1\" \/><\/div><div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\">Funciona globalmente, sin restricciones a ning\u00fan pa\u00eds o regi\u00f3n del mundo!<\/div><\/div><div aria-hidden=\"true\">\u00a0<\/div><div aria-hidden=\"true\"><div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\"><img decoding=\"async\" data-attachment-id=\"7325\" data-permalink=\"https:\/\/enderg.com\/es\/?attachment_id=7325\" data-orig-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?fit=512%2C512&amp;ssl=1\" data-orig-size=\"512,512\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"tick wd\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?fit=512%2C512&amp;ssl=1\" class=\"alignleft wp-image-7325 ls-is-cached lazyloaded\" src=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=25%2C25&amp;ssl=1\" sizes=\"(max-width: 25px) 100vw, 25px\" srcset=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=416%2C416&amp;ssl=1 416w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=50%2C50&amp;ssl=1 50w\" alt=\"\" width=\"25\" height=\"25\" data-medium-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?fit=300%2C300&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=25%2C25&amp;ssl=1\" \/><\/div><div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\">Puede ser &#039;<strong>Agregado<\/strong>&#039; para usted &#039;<strong>Principal propio<\/strong>&#039; cuenta as\u00ed como cuentas de &#039;<strong>Amigos de la familia<\/strong>&#039;\u00a1Qui\u00e9n usa tu consola!<\/div><\/div><\/div><div aria-hidden=\"true\">\u00a0<\/div><div aria-hidden=\"true\"><div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\"><img decoding=\"async\" data-attachment-id=\"7325\" data-permalink=\"https:\/\/enderg.com\/es\/?attachment_id=7325\" data-orig-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?fit=512%2C512&amp;ssl=1\" data-orig-size=\"512,512\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"tick wd\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?fit=512%2C512&amp;ssl=1\" class=\"alignleft wp-image-7325 ls-is-cached lazyloaded\" src=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=25%2C25&amp;ssl=1\" sizes=\"(max-width: 25px) 100vw, 25px\" srcset=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=416%2C416&amp;ssl=1 416w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=50%2C50&amp;ssl=1 50w\" alt=\"\" width=\"25\" height=\"25\" data-medium-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?fit=300%2C300&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=25%2C25&amp;ssl=1\" \/><\/div><div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\">Puede ser &#039;<strong>Agregado<\/strong>&#039; a\u00a0<strong>1 consola<\/strong>!\u00a0<strong>1<\/strong>\u00a0<strong>PS4<\/strong>\u00a0o\u00a0<strong>1<\/strong>\u00a0<strong>PS5<\/strong>!<\/div><div aria-hidden=\"true\"><div aria-hidden=\"true\">\u00a0<\/div><div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\"><img decoding=\"async\" data-attachment-id=\"7325\" data-permalink=\"https:\/\/enderg.com\/es\/?attachment_id=7325\" data-orig-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?fit=512%2C512&amp;ssl=1\" data-orig-size=\"512,512\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"tick wd\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?fit=512%2C512&amp;ssl=1\" class=\"alignleft wp-image-7325 ls-is-cached lazyloaded smush-image-5\" src=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=25%2C25&amp;ssl=1\" sizes=\"(max-width: 25px) 100vw, 25px\" srcset=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=416%2C416&amp;ssl=1 416w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=50%2C50&amp;ssl=1 50w\" alt=\"\" width=\"25\" height=\"25\" data-medium-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?fit=300%2C300&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=25%2C25&amp;ssl=1\" \/><\/div><div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\">\u00a1Viene con garant\u00eda de por vida!<\/div><\/div><\/div><div class=\"jetpack-boost-guide\" data-jetpack-boost-guide-id=\"105\"><div class=\"guide micro svelte-1828btn\"><div class=\"previews svelte-1828btn\"><div class=\"interaction-area normal svelte-18vhu7m\"><div class=\"bubble svelte-18vhu7m\"><div class=\"bubble-inner svelte-18vhu7m\"><div class=\"label\">\u00a0<\/div><\/div><\/div><\/div><\/div><\/div><\/div><p><img decoding=\"async\" data-attachment-id=\"13815\" data-permalink=\"https:\/\/enderg.com\/es\/?attachment_id=13815\" data-orig-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2024\/01\/lifetime.png?fit=512%2C512&amp;ssl=1\" data-orig-size=\"512,512\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"lifetime\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2024\/01\/lifetime.png?fit=512%2C512&amp;ssl=1\" class=\"aligncenter wp-image-13815 ls-is-cached lazyloaded\" src=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2024\/01\/lifetime.png?resize=112%2C112&amp;ssl=1\" alt=\"\" width=\"112\" height=\"112\" data-medium-file=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2024\/01\/lifetime.png?fit=300%2C300&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2024\/01\/lifetime.png?resize=112%2C112&amp;ssl=1\" \/><\/p><p>*\u00a1Este servicio no contiene ning\u00fan c\u00f3digo!\u00a0<\/p><p>*Only English &amp; Japanese languages are supported<\/p><\/div><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\">\n<div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\"><img decoding=\"async\" class=\"alignleft wp-image-7325 lazyload\" data-src=\"https:\/\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd-300x300.png\" alt=\"\" width=\"25\" height=\"25\" data-srcset=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=416%2C416&amp;ssl=1 416w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=50%2C50&amp;ssl=1 50w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?w=512&amp;ssl=1 512w\" data-sizes=\"(max-width: 25px) 100vw, 25px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 25px; --smush-placeholder-aspect-ratio: 25\/25;\" \/><\/div>\n<div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\">Ahorra casi la mitad del precio regular!<\/div>\n<div aria-hidden=\"true\"><\/div>\n<div aria-hidden=\"true\">\n<div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\"><img decoding=\"async\" class=\"alignleft wp-image-7325 lazyload\" data-src=\"https:\/\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd-300x300.png\" alt=\"\" width=\"25\" height=\"25\" data-srcset=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=416%2C416&amp;ssl=1 416w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=50%2C50&amp;ssl=1 50w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?w=512&amp;ssl=1 512w\" data-sizes=\"(max-width: 25px) 100vw, 25px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 25px; --smush-placeholder-aspect-ratio: 25\/25;\" \/><\/div>\n<div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\">Funciona globalmente, sin restricciones a ning\u00fan pa\u00eds o regi\u00f3n del mundo!<\/div>\n<\/div>\n<div aria-hidden=\"true\"><\/div>\n<div aria-hidden=\"true\">\n<div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\"><img decoding=\"async\" class=\"alignleft wp-image-7325 lazyload\" data-src=\"https:\/\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd-300x300.png\" alt=\"\" width=\"25\" height=\"25\" data-srcset=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=416%2C416&amp;ssl=1 416w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=50%2C50&amp;ssl=1 50w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?w=512&amp;ssl=1 512w\" data-sizes=\"(max-width: 25px) 100vw, 25px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 25px; --smush-placeholder-aspect-ratio: 25\/25;\" \/><\/div>\n<div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\">Puede ser &#039;<strong>Agregado<\/strong>&#039; para usted &#039;<strong>Principal propio<\/strong>&#039; cuenta as\u00ed como cuentas de &#039;<strong>Amigos de la familia<\/strong>&#039; que usan tu consola!<\/div>\n<\/div>\n<\/div>\n<div aria-hidden=\"true\"><\/div>\n<div aria-hidden=\"true\">\n<div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\"><img decoding=\"async\" class=\"alignleft wp-image-7325 lazyload\" data-src=\"https:\/\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd-300x300.png\" alt=\"\" width=\"25\" height=\"25\" data-srcset=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=416%2C416&amp;ssl=1 416w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?resize=50%2C50&amp;ssl=1 50w, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/tick-wd.png?w=512&amp;ssl=1 512w\" data-sizes=\"(max-width: 25px) 100vw, 25px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 25px; --smush-placeholder-aspect-ratio: 25\/25;\" \/><\/div>\n<div class=\"sc-iqAclL gFwbga\" aria-hidden=\"true\">Puede ser &#039;<strong>Agregado<\/strong>&#039; a <strong>1 consola<\/strong>! <strong>1<\/strong> <strong>PS5<\/strong>!<\/div>\n<\/div>","protected":false},"featured_media":11443,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"product_brand":[],"product_cat":[1375,1377,1374],"product_tag":[],"class_list":{"0":"post-12912","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pc","7":"product_cat-playstation","8":"product_cat-xbox","10":"first","11":"instock","12":"sale","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable","17":"has-default-attributes"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Marvel&#039;s Spider-Man 2 - EnderG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enderg.com\/es\/product\/buy-marvels-spider-man-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marvel&#039;s Spider-Man 2\" \/>\n<meta property=\"og:description\" content=\"Save almost half of the regular price!    Works Globally, with no restrictions to any country or region in the world!     Can be &#039;Added&#039; to your &#039;Own Main&#039; account as well as accounts of &#039;Family &amp; Friends&#039; who use your console!      Can be &#039;Added&#039; to 1 Console! 1 PS5!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enderg.com\/es\/product\/buy-marvels-spider-man-2\/\" \/>\n<meta property=\"og:site_name\" content=\"EnderG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Endergg1\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-30T10:52:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/09\/cover_large-e1695930545262.webp?fit=600%2C671&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"671\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/enderg.com\\\/product\\\/buy-marvels-spider-man-2\\\/\",\"url\":\"https:\\\/\\\/enderg.com\\\/product\\\/buy-marvels-spider-man-2\\\/\",\"name\":\"Marvel's Spider-Man 2 - EnderG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enderg.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/enderg.com\\\/product\\\/buy-marvels-spider-man-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/enderg.com\\\/product\\\/buy-marvels-spider-man-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/enderg.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/cover_large-e1695930545262.webp?fit=600%2C671&ssl=1\",\"datePublished\":\"2023-12-25T23:50:06+00:00\",\"dateModified\":\"2024-09-30T10:52:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/enderg.com\\\/product\\\/buy-marvels-spider-man-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/enderg.com\\\/product\\\/buy-marvels-spider-man-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/enderg.com\\\/product\\\/buy-marvels-spider-man-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/enderg.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/cover_large-e1695930545262.webp?fit=600%2C671&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/enderg.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/cover_large-e1695930545262.webp?fit=600%2C671&ssl=1\",\"width\":600,\"height\":671},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/enderg.com\\\/product\\\/buy-marvels-spider-man-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/enderg.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/enderg.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Marvel&#8217;s Spider-Man 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/enderg.com\\\/#website\",\"url\":\"https:\\\/\\\/enderg.com\\\/\",\"name\":\"EnderG\",\"description\":\"Cheaper Is What We Do!\",\"publisher\":{\"@id\":\"https:\\\/\\\/enderg.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/enderg.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/enderg.com\\\/#organization\",\"name\":\"EnderG\",\"url\":\"https:\\\/\\\/enderg.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/enderg.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/enderg.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/222222222221.png\",\"contentUrl\":\"https:\\\/\\\/enderg.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/222222222221.png\",\"width\":512,\"height\":512,\"caption\":\"EnderG\"},\"image\":{\"@id\":\"https:\\\/\\\/enderg.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Endergg1\\\/\",\"https:\\\/\\\/www.instagram.com\\\/enderg01\",\"https:\\\/\\\/www.youtube.com\\\/@enderg-com\"],\"description\":\"Cheaper Gaming is what we do!\",\"legalName\":\"Vandar Limited\",\"foundingDate\":\"2022-06-21\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Marvel&#039;s Spider-Man 2 - EnderG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enderg.com\/es\/product\/buy-marvels-spider-man-2\/","og_locale":"es_ES","og_type":"article","og_title":"Marvel's Spider-Man 2","og_description":"Save almost half of the regular price!    Works Globally, with no restrictions to any country or region in the world!     Can be 'Added' to your 'Own Main' account as well as accounts of 'Family &amp; Friends' who use your console!      Can be 'Added' to 1 Console! 1 PS5!","og_url":"https:\/\/enderg.com\/es\/product\/buy-marvels-spider-man-2\/","og_site_name":"EnderG","article_publisher":"https:\/\/www.facebook.com\/Endergg1\/","article_modified_time":"2024-09-30T10:52:17+00:00","og_image":[{"width":600,"height":671,"url":"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/09\/cover_large-e1695930545262.webp?fit=600%2C671&ssl=1","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/enderg.com\/product\/buy-marvels-spider-man-2\/","url":"https:\/\/enderg.com\/product\/buy-marvels-spider-man-2\/","name":"Marvel&#039;s Spider-Man 2 - EnderG","isPartOf":{"@id":"https:\/\/enderg.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enderg.com\/product\/buy-marvels-spider-man-2\/#primaryimage"},"image":{"@id":"https:\/\/enderg.com\/product\/buy-marvels-spider-man-2\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/09\/cover_large-e1695930545262.webp?fit=600%2C671&ssl=1","datePublished":"2023-12-25T23:50:06+00:00","dateModified":"2024-09-30T10:52:17+00:00","breadcrumb":{"@id":"https:\/\/enderg.com\/product\/buy-marvels-spider-man-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enderg.com\/product\/buy-marvels-spider-man-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/enderg.com\/product\/buy-marvels-spider-man-2\/#primaryimage","url":"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/09\/cover_large-e1695930545262.webp?fit=600%2C671&ssl=1","contentUrl":"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/09\/cover_large-e1695930545262.webp?fit=600%2C671&ssl=1","width":600,"height":671},{"@type":"BreadcrumbList","@id":"https:\/\/enderg.com\/product\/buy-marvels-spider-man-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/enderg.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/enderg.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Marvel&#8217;s Spider-Man 2"}]},{"@type":"WebSite","@id":"https:\/\/enderg.com\/#website","url":"https:\/\/enderg.com\/","name":"EnderG","description":"\u00a1M\u00e1s barato es lo que hacemos!","publisher":{"@id":"https:\/\/enderg.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enderg.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/enderg.com\/#organization","name":"EnderG","url":"https:\/\/enderg.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/enderg.com\/#\/schema\/logo\/image\/","url":"https:\/\/enderg.com\/wp-content\/uploads\/2023\/03\/222222222221.png","contentUrl":"https:\/\/enderg.com\/wp-content\/uploads\/2023\/03\/222222222221.png","width":512,"height":512,"caption":"EnderG"},"image":{"@id":"https:\/\/enderg.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Endergg1\/","https:\/\/www.instagram.com\/enderg01","https:\/\/www.youtube.com\/@enderg-com"],"description":"\u00a1Juegos m\u00e1s baratos es lo que hacemos!","legalName":"Vandar Limited","foundingDate":"2022-06-21"}]}},"jetpack_publicize_connections":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":6181,"url":"https:\/\/enderg.com\/es\/product\/the-last-of-us-part-i\/","url_meta":{"origin":12912,"position":0},"title":"El \u00faltimo de nosotros Parte I","author":"nazhad722","date":"24\/03\/2023","format":false,"excerpt":"Entrega r\u00e1pida La entrega puede tardar entre 5 y 20 minutos, seg\u00fan su lugar en nuestra cola. \u00a1Su pedido ser\u00e1 &#039;reembolsado autom\u00e1ticamente&#039; en caso de que no se entregue despu\u00e9s de 12 horas!","rel":"","context":"Con 1 comentario","block_context":{"text":"Con 1 comentario","link":"https:\/\/enderg.com\/es\/product\/the-last-of-us-part-i\/#comments"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/03\/eEczyEMDd2BLa3dtkGJVE9Id.jpg?fit=1024%2C1024&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/03\/eEczyEMDd2BLa3dtkGJVE9Id.jpg?fit=1024%2C1024&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/03\/eEczyEMDd2BLa3dtkGJVE9Id.jpg?fit=1024%2C1024&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/03\/eEczyEMDd2BLa3dtkGJVE9Id.jpg?fit=1024%2C1024&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":7427,"url":"https:\/\/enderg.com\/es\/product\/god-of-war-ragnarok\/","url_meta":{"origin":12912,"position":1},"title":"God of War Ragnar\u00f6k","author":"nazhad722","date":"09\/04\/2023","format":false,"excerpt":"Entrega r\u00e1pida La entrega puede tardar entre 5 y 20 minutos, seg\u00fan su lugar en nuestra cola. \u00a1Su pedido ser\u00e1 &#039;reembolsado autom\u00e1ticamente&#039; en caso de que no se entregue despu\u00e9s de 12 horas!","rel":"","context":"Con 1 comentario","block_context":{"text":"Con 1 comentario","link":"https:\/\/enderg.com\/es\/product\/god-of-war-ragnarok\/#comments"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/4xJ8XB3bi888QTLZYdl7Oi0s.jpg?fit=1024%2C1024&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/4xJ8XB3bi888QTLZYdl7Oi0s.jpg?fit=1024%2C1024&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/4xJ8XB3bi888QTLZYdl7Oi0s.jpg?fit=1024%2C1024&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/4xJ8XB3bi888QTLZYdl7Oi0s.jpg?fit=1024%2C1024&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":7772,"url":"https:\/\/enderg.com\/es\/product\/the-last-of-us-part-ii\/","url_meta":{"origin":12912,"position":2},"title":"The Last of Us Part II","author":"nazhad722","date":"14\/04\/2023","format":false,"excerpt":"Entrega r\u00e1pida La entrega puede tardar entre 5 y 20 minutos, seg\u00fan su lugar en nuestra cola. \u00a1Su pedido ser\u00e1 &#039;reembolsado autom\u00e1ticamente&#039; en caso de que no se entregue despu\u00e9s de 12 horas!","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/w48z6bzefZPrRcJHc7L8SO66.jpg?fit=1024%2C1024&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/w48z6bzefZPrRcJHc7L8SO66.jpg?fit=1024%2C1024&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/w48z6bzefZPrRcJHc7L8SO66.jpg?fit=1024%2C1024&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/w48z6bzefZPrRcJHc7L8SO66.jpg?fit=1024%2C1024&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":7936,"url":"https:\/\/enderg.com\/es\/product\/the-sims-4-seasons\/","url_meta":{"origin":12912,"position":3},"title":"The Sims\u2122 4 Seasons","author":"nazhad722","date":"20\/04\/2023","format":false,"excerpt":"Entrega r\u00e1pidaLa entrega puede demorar entre 5 y 20 minutos, seg\u00fan su lugar en nuestra cola.\u00a1Su pedido ser\u00e1 &#039;reembolsado autom\u00e1ticamente&#039; en caso de que no se entregue despu\u00e9s de 12 horas!","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/11307l-ZLoS5SuVsN-lGMiENi9CwURRnxnz1CfFexMYeZW4oBUS007qh0Zoa82dyaL9SCx1nlLgT0IOMLNS60e4TDncK8rvL.jpg?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/11307l-ZLoS5SuVsN-lGMiENi9CwURRnxnz1CfFexMYeZW4oBUS007qh0Zoa82dyaL9SCx1nlLgT0IOMLNS60e4TDncK8rvL.jpg?fit=1200%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/11307l-ZLoS5SuVsN-lGMiENi9CwURRnxnz1CfFexMYeZW4oBUS007qh0Zoa82dyaL9SCx1nlLgT0IOMLNS60e4TDncK8rvL.jpg?fit=1200%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/11307l-ZLoS5SuVsN-lGMiENi9CwURRnxnz1CfFexMYeZW4oBUS007qh0Zoa82dyaL9SCx1nlLgT0IOMLNS60e4TDncK8rvL.jpg?fit=1200%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/11307l-ZLoS5SuVsN-lGMiENi9CwURRnxnz1CfFexMYeZW4oBUS007qh0Zoa82dyaL9SCx1nlLgT0IOMLNS60e4TDncK8rvL.jpg?fit=1200%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8009,"url":"https:\/\/enderg.com\/es\/product\/sudden-strike-4\/","url_meta":{"origin":12912,"position":4},"title":"Sudden Strike 4","author":"nazhad722","date":"25\/04\/2023","format":false,"excerpt":"Entrega r\u00e1pidaLa entrega puede demorar entre 5 y 20 minutos, seg\u00fan su lugar en nuestra cola.\u00a1Su pedido ser\u00e1 &#039;reembolsado autom\u00e1ticamente&#039; en caso de que no se entregue despu\u00e9s de 12 horas!","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/04\/Sudden_Strike_4_cover.jpg?fit=316%2C316&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5954,"url":"https:\/\/enderg.com\/es\/product\/star-wars-jedi-survivor\/","url_meta":{"origin":12912,"position":5},"title":"STAR WARS Jedi: Superviviente\u2122","author":"nazhad722","date":"21\/03\/2023","format":false,"excerpt":"Entrega r\u00e1pidaLa entrega puede demorar entre 5 y 20 minutos, seg\u00fan su lugar en nuestra cola.\u00a1Su pedido ser\u00e1 &#039;reembolsado autom\u00e1ticamente&#039; en caso de que no se entregue despu\u00e9s de 12 horas!","rel":"","context":"Con 1 comentario","block_context":{"text":"Con 1 comentario","link":"https:\/\/enderg.com\/es\/product\/star-wars-jedi-survivor\/#comments"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/03\/sw-jedi-survivor-key-art-1080x1080_c38222d5.jpeg?fit=1080%2C1080&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/03\/sw-jedi-survivor-key-art-1080x1080_c38222d5.jpeg?fit=1080%2C1080&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/03\/sw-jedi-survivor-key-art-1080x1080_c38222d5.jpeg?fit=1080%2C1080&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/03\/sw-jedi-survivor-key-art-1080x1080_c38222d5.jpeg?fit=1080%2C1080&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/enderg.com\/wp-content\/uploads\/2023\/03\/sw-jedi-survivor-key-art-1080x1080_c38222d5.jpeg?fit=1080%2C1080&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/enderg.com\/es\/wp-json\/wp\/v2\/product\/12912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enderg.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/enderg.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/enderg.com\/es\/wp-json\/wp\/v2\/comments?post=12912"}],"version-history":[{"count":30,"href":"https:\/\/enderg.com\/es\/wp-json\/wp\/v2\/product\/12912\/revisions"}],"predecessor-version":[{"id":35128,"href":"https:\/\/enderg.com\/es\/wp-json\/wp\/v2\/product\/12912\/revisions\/35128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enderg.com\/es\/wp-json\/wp\/v2\/media\/11443"}],"wp:attachment":[{"href":"https:\/\/enderg.com\/es\/wp-json\/wp\/v2\/media?parent=12912"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/enderg.com\/es\/wp-json\/wp\/v2\/product_brand?post=12912"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/enderg.com\/es\/wp-json\/wp\/v2\/product_cat?post=12912"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/enderg.com\/es\/wp-json\/wp\/v2\/product_tag?post=12912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}